{"id":204824,"date":"2026-08-31T15:52:52","date_gmt":"2026-08-31T15:52:52","guid":{"rendered":"https:\/\/rosarios4.com\/lhistoire-de-rosarios-4\/"},"modified":"2026-08-31T15:52:53","modified_gmt":"2026-08-31T15:52:53","slug":"lhistoire-de-rosarios-4","status":"publish","type":"page","link":"https:\/\/rosarios4.com\/fr\/lhistoire-de-rosarios-4\/","title":{"rendered":"L&#8217;histoire de Ros\u00e1rios 4"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column 0=&#8221;&#8221;][vc_single_image image=&#8221;10769&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10744&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221; css=&#8221;.vc_custom_1509127495172{padding-top: 30px !important;padding-right: 30px !important;padding-bottom: 30px !important;padding-left: 30px !important;background-color: #edd2c3 !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1573464604127{margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]<\/p>\n<h3>UNE HISTOIRE QUI A COMMENC\u00c9 DEUX G\u00c9N\u00c9RATIONS AVANT LA CR\u00c9ATION DE L\u2019ENTREPRISE<\/h3>\n<p>C\u2019est au sommet la ville de Mira de Aire que se trouve la filature Ros\u00e1rios 4, pench\u00e9e sur les pentes de la serre qui contourne la petite ville. L\u2019histoire de Ros\u00e1rios 4 a commenc\u00e9 pr\u00e9cis\u00e9ment l\u00e0, \u00e0 la fin des ann\u00e9es 70, lorsque l\u2019atelier de teinture donnait de la couleur aux fils par les mains de Manuel Delfim do Ros\u00e1rio, fondateur de l\u2019entreprise et ma\u00eetre teinturier.<\/p>\n<p>Mais le travailler la laine et les fils faisait d\u00e9j\u00e0 partie de l\u2019histoire familiale depuis longtemps \u2013 d\u00e8s les ann\u00e9es 30, les grands-parents maternels et les oncles de Manuel Delfim cardaient et filaient de la laine, utilis\u00e9e pour confectionner des bonnets et des couvertures. Sa m\u00e8re travaillait \u00e9galement dans ce secteur: elle \u00e9tait tisserande et r\u00e9alisait des couvertures sur des m\u00e9tiers \u00e0 tisser en bois. Aujourd\u2019hui encore, ces couvertures sont toujours des ouvrages embl\u00e9matiques de la tradition r\u00e9gionale.<\/p>\n<p>\u00c0 cette \u00e9poque, l\u2019industrie textile \u00e9tait l\u2019un des principaux moteurs \u00e9conomiques de la r\u00e9gion et le fondateur, tout comme son \u00e9pouse Concei\u00e7\u00e3o, travaillaient dans une usine textile. Le savoir-faire transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration, enrichi par leur exp\u00e9rience professionnelle et connaissances techniques, a ainsi conduit \u00e0 la cr\u00e9ation de Ros\u00e1rios 4.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1512472196558{margin-bottom: 0px !important;padding-top: 0px !important;}&#8221;]<\/p>\n<h3>LE PREMIER FIL \u00c0 TRICOTER<\/h3>\n<p>\u00c0 ses d\u00e9buts, l\u2019activit\u00e9 de Ros\u00e1rios 4 \u00e9tait consacr\u00e9e principalement \u00e0 la teinturerie, lorsque des fils de laine et des fibres synth\u00e9tiques \u00e9taient teints afin de r\u00e9pondre aux besoins des nombreuses usines de\u00a0 bonneterie de la r\u00e9gion.<\/p>\n<p>L\u2019entreprise s\u2019est toutefois rapidement d\u00e9velopp\u00e9e. \u00c0 l\u2019activit\u00e9 de teinturerie s\u2019est ajout\u00e9e la filature, marquant le d\u00e9but de la production de fils \u00e0 tricoter \u00e0 partir des ann\u00e9es 80. Catita, un fil en acrylique, fut le premier fil \u00e0 tricoter \u00e0 \u00eatre produit par Ros\u00e1rios 4. Aujourd\u2019hui, plus de trente ans plus tard, il fait toujours partie de la collection de la marque et reste, pour un grand nombre de tricoteuses, un v\u00e9ritable classique et un fil de r\u00e9f\u00e9rence.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10749&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1509127579278{padding-top: 30px !important;padding-right: 30px !important;padding-bottom: 30px !important;padding-left: 30px !important;background-color: #f3f3f3 !important;}&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; css=&#8221;.vc_custom_1509127860536{padding-top: 30px !important;padding-bottom: 30px !important;background-color: #f4ede7 !important;}&#8221;][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1491478082302{padding-top: 0px !important;padding-right: 2% !important;padding-left: 12% !important;}&#8221; el_id=&#8221;historia_sec2_col1&#8243;][\/vc_column][vc_column width=&#8221;4\/6&#8243;][vc_column_text css=&#8221;.vc_custom_1512472237445{margin-bottom: 0px !important;padding-top: 30px !important;}&#8221;]<\/p>\n<h3>ARRAIOLOS, FIL DE TAPISSERIE ET FIL \u00c0 BRODER<\/h3>\n<p>La tapisserie d\u2019Arraiolos est l\u2019une des traditions de broderie les plus anciennes et les plus importantes du Portugal. R\u00e9alis\u00e9e avec un fil 100 % laine sur une toile de jute, elle cr\u00e9e motifs et dessins caract\u00e9ristiques de ce genre de tapisserie.<\/p>\n<p>Ce fut en 1995 que Ros\u00e1rios 4 a commenc\u00e9 la production du fil Arraiolos 100 % laine, avec la certification Pure New Wool et qui est, aujourd\u2019hui, une r\u00e9f\u00e9rence reconnue, tant pour sa qualit\u00e9 comme pour son exceptionnel nuancier &#8211;\u00a0 plus de 400 coloris &#8211; une v\u00e9ritable source d\u2019inspiration \u00e0 la cr\u00e9ativit\u00e9 et \u00e0 la pr\u00e9servation d\u2019une tradition centenaire.<\/p>\n<p>C\u2019est fut \u00e9galement \u00e0 cette \u00e9poque que Ros\u00e1rios 4 a commenc\u00e9 \u00e0 produire des fils pour tapisserie et a enrichi sa collection avec des fils destin\u00e9s \u00e0 la broderie.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10759&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1509129736994{padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1512472304345{margin-bottom: 0px !important;padding-top: 30px !important;}&#8221;]<\/p>\n<h3>UNE COLLECTION INNOVATRICE ET TOUJOURS PLUS IMPORTANTE DE FILS EN FIBRES NATURELLES<\/h3>\n<p>L\u2019engagement de Ros\u00e1rios 4 en faveur des fils en fibres naturelles fait partie de la politique et des principes de l\u2019entreprise, en r\u00e9ponse non seulement \u00e0 une demande croissante de fils de haute qualit\u00e9, mais qui est \u00e9galement le reflet d\u2019une philosophie responsable et respectueuse de l\u2019environnement, qui caract\u00e9rise toutes les activit\u00e9s de l\u2019entreprise.<\/p>\n<p>Ainsi, la Ecofriendly Collection, marque d\u00e9pos\u00e9e de Ros\u00e1rios 4, devient plus importante, collection apr\u00e8s collection, en pr\u00e9sentant des fils aux compositions les plus vari\u00e9es: laine, coton, lin, soie, fibre de ma\u00efs, bambou, prot\u00e9ine de lait, canne \u00e0 sucre et li\u00e8ge \u2013 une mati\u00e8re v\u00e9g\u00e9tale dont le Portugal est le plus grand producteur mondial.<\/p>\n<p>En compl\u00e9ment de ses fils en fibres naturelles, Ros\u00e1rios 4 a \u00e9galement d\u00e9velopp\u00e9 une collection de fils teints naturellement, \u00e9labor\u00e9s \u00e0 partir de colorants d\u2019origine v\u00e9g\u00e9tale ou animale.<\/p>\n<h3>DE NOUVEAUX PRODUITS \u00c0 CHAQUE SAISON<\/h3>\n<p>Deux fois par an, Ros\u00e1rios 4 lance de nouvelles collections de fils, d\u00e9velopp\u00e9es en suivant les tendances actuelles et les souhaits du march\u00e9. Le salon Handarbeit &amp; Hobby, \u00e0 Cologne (Allemagne), sur lequel Ros\u00e1rios 4 est pr\u00e9sente depuis 2003, reste l\u2019un des principaux rendez-vous pour la pr\u00e9sentation de ses nouveaut\u00e9s.<\/p>\n<p>L\u2019ann\u00e9e de 2017 ne fut exception : en plus de ses nouvelles collections de fils, Ros\u00e1rios 4 y a pr\u00e9sent\u00e9 un kit de teinture permettant de teindre des fils \u00e0 domicile. Ce nouveau produit a \u00e9t\u00e9 accueilli avec un grand enthousiasme, tant sur le march\u00e9 national qu\u2019\u00e0 l\u2019international.<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1509129748639{background-color: #f4ede7 !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1512472340842{margin-bottom: 0px !important;padding-top: 30px !important;}&#8221;]<\/p>\n<h3>\u00c0 LA CONQU\u00caTE DE NOUVEAUX MARCH\u00c9S<\/h3>\n<p>Le changement de mill\u00e9naire a \u00e9galement apport\u00e9 un nouveau regard vers les march\u00e9s internationaux, donnant ainsi le point de d\u00e9part au processus d\u2019internationalisation de l\u2019entreprise.<\/p>\n<p>Depuis lors, Ros\u00e1rios 4 a progressivement conquis de nombreux march\u00e9s, non seulement en Europe, mais aussi en Asie, en Australie et sur le continent am\u00e9ricain.<\/p>\n<p>En proposant des produits de qualit\u00e9 \u00e0 forte valeur certifi\u00e9e, Ros\u00e1rios 4 s\u2019est affirm\u00e9e comme une marque de r\u00e9f\u00e9rence. Son statut de fabricant constitue plus que jamais un v\u00e9ritable atout et un facteur de diff\u00e9renciation, lui permettant d\u2019apporter des r\u00e9ponses personnalis\u00e9es et de d\u00e9velopper des solutions adapt\u00e9es aux besoins sp\u00e9cifiques de chacun de ses clients.<br \/>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10764&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column 0=&#8221;&#8221;][vc_single_image image=&#8221;10769&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;10744&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221; css=&#8221;.vc_custom_1509127495172{padding-top: 30px !important;padding-right: 30px !important;padding-bottom:&#8230;<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-204824","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/pages\/204824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/comments?post=204824"}],"version-history":[{"count":3,"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/pages\/204824\/revisions"}],"predecessor-version":[{"id":204827,"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/pages\/204824\/revisions\/204827"}],"wp:attachment":[{"href":"https:\/\/rosarios4.com\/fr\/wp-json\/wp\/v2\/media?parent=204824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}